{"id":474,"date":"2012-12-14T11:14:42","date_gmt":"2012-12-14T13:14:42","guid":{"rendered":"http:\/\/www.encontrabebedouro.com.br\/noticias\/?p=474"},"modified":"2019-04-29T17:12:15","modified_gmt":"2019-04-29T20:12:15","slug":"gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro","status":"publish","type":"post","link":"https:\/\/www.encontrabebedouro.com.br\/sobre\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\/","title":{"rendered":"GCM aumenta patrulhamento na regi\u00e3o central de Bebedouro"},"content":{"rendered":"<div class=\"e7593ce1d9603c7e10386aa266b728a9\" data-index=\"1\" style=\"float: left; margin: 15px 15px 15px 0;\">\n<!-- EBR \/Novo-Bairro\/ 300x250 - pub-85 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:300px;height:250px\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"4691134188\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n\n<\/div>\n<p>A Guarda Civil Municipal vai aumentar o patrulhamento na regi\u00e3o central da cidade, devido \u00e0s festas de final de ano.<\/p>\n<p>O comandante da GCM, Luiz Roberto Cardos, disse \u201co objetivo principal \u00e9 diminuir o numero de furtos e roubos. O n\u00famero de pessoas circulando pelo com\u00e9rcio aumenta neste per\u00edodo do ano, e os ladr\u00f5es aproveitam este momento\u201d.<\/p>\n<p><em>Fonte: Prefeitura Bebedouro<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A Guarda Civil Municipal vai aumentar o patrulhamento na regi\u00e3o central da cidade, devido \u00e0s festas de final de ano. O comandante da GCM, Luiz Roberto Cardos, disse \u201co objetivo principal \u00e9 diminuir o numero de furtos e roubos. O n\u00famero de pessoas circulando pelo com\u00e9rcio aumenta neste per\u00edodo do ano, e os ladr\u00f5es aproveitam este momento\u201d. Fonte: Prefeitura Bebedouro<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-474","post","type-post","status-publish","format-standard","hentry","category-noticias-bebedouro"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"A Guarda Civil Municipal vai aumentar o patrulhamento na regi\u00e3o central da cidade, devido \u00e0s festas de final de ano. O comandante da GCM, Luiz Roberto Cardos, disse \u201co objetivo principal \u00e9 diminuir o numero de furtos e roubos. O n\u00famero de pessoas circulando pelo com\u00e9rcio aumenta neste per\u00edodo do ano, e os ladr\u00f5es aproveitam\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Encontra Bebedouro\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.encontrabebedouro.com.br\/sobre\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Encontra Bebedouro | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Bebedouro e regi\u00e3o\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"GCM aumenta patrulhamento na regi\u00e3o central de Bebedouro | Encontra Bebedouro\" \/>\n\t\t<meta property=\"og:description\" content=\"A Guarda Civil Municipal vai aumentar o patrulhamento na regi\u00e3o central da cidade, devido \u00e0s festas de final de ano. O comandante da GCM, Luiz Roberto Cardos, disse \u201co objetivo principal \u00e9 diminuir o numero de furtos e roubos. O n\u00famero de pessoas circulando pelo com\u00e9rcio aumenta neste per\u00edodo do ano, e os ladr\u00f5es aproveitam\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.encontrabebedouro.com.br\/sobre\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-12-14T13:14:42+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-04-29T20:12:15+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"GCM aumenta patrulhamento na regi\u00e3o central de Bebedouro | Encontra Bebedouro\" \/>\n\t\t<meta name=\"twitter:description\" content=\"A Guarda Civil Municipal vai aumentar o patrulhamento na regi\u00e3o central da cidade, devido \u00e0s festas de final de ano. O comandante da GCM, Luiz Roberto Cardos, disse \u201co objetivo principal \u00e9 diminuir o numero de furtos e roubos. O n\u00famero de pessoas circulando pelo com\u00e9rcio aumenta neste per\u00edodo do ano, e os ladr\u00f5es aproveitam\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\\\/#article\",\"name\":\"GCM aumenta patrulhamento na regi\\u00e3o central de Bebedouro | Encontra Bebedouro\",\"headline\":\"GCM aumenta patrulhamento na regi\\u00e3o central de Bebedouro\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/author\\\/ebebedouro\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/#organization\"},\"datePublished\":\"2012-12-14T11:14:42-02:00\",\"dateModified\":\"2019-04-29T17:12:15-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias Bebedouro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre#listItem\",\"position\":1,\"name\":\"Dom\\u00e9stica\",\"item\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/noticias-bebedouro\\\/#listItem\",\"name\":\"Not\\u00edcias Bebedouro\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/noticias-bebedouro\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias Bebedouro\",\"item\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/noticias-bebedouro\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\\\/#listItem\",\"name\":\"GCM aumenta patrulhamento na regi\\u00e3o central de Bebedouro\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre#listItem\",\"name\":\"Dom\\u00e9stica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\\\/#listItem\",\"position\":3,\"name\":\"GCM aumenta patrulhamento na regi\\u00e3o central de Bebedouro\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/noticias-bebedouro\\\/#listItem\",\"name\":\"Not\\u00edcias Bebedouro\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/#organization\",\"name\":\"Encontra Bebedouro\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Bebedouro e regi\\u00e3o\",\"url\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/author\\\/ebebedouro\\\/#author\",\"url\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/author\\\/ebebedouro\\\/\",\"name\":\"Encontra Bebedouro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Encontra Bebedouro\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\\\/#webpage\",\"url\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\\\/\",\"name\":\"GCM aumenta patrulhamento na regi\\u00e3o central de Bebedouro | Encontra Bebedouro\",\"description\":\"A Guarda Civil Municipal vai aumentar o patrulhamento na regi\\u00e3o central da cidade, devido \\u00e0s festas de final de ano. O comandante da GCM, Luiz Roberto Cardos, disse \\u201co objetivo principal \\u00e9 diminuir o numero de furtos e roubos. O n\\u00famero de pessoas circulando pelo com\\u00e9rcio aumenta neste per\\u00edodo do ano, e os ladr\\u00f5es aproveitam\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/author\\\/ebebedouro\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/author\\\/ebebedouro\\\/#author\"},\"datePublished\":\"2012-12-14T11:14:42-02:00\",\"dateModified\":\"2019-04-29T17:12:15-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/\",\"name\":\"Encontra Bebedouro\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Bebedouro e regi\\u00e3o\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"GCM aumenta patrulhamento na regi\u00e3o central de Bebedouro | Encontra Bebedouro","description":"A Guarda Civil Municipal vai aumentar o patrulhamento na regi\u00e3o central da cidade, devido \u00e0s festas de final de ano. O comandante da GCM, Luiz Roberto Cardos, disse \u201co objetivo principal \u00e9 diminuir o numero de furtos e roubos. O n\u00famero de pessoas circulando pelo com\u00e9rcio aumenta neste per\u00edodo do ano, e os ladr\u00f5es aproveitam","canonical_url":"https:\/\/www.encontrabebedouro.com.br\/sobre\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\/#article","name":"GCM aumenta patrulhamento na regi\u00e3o central de Bebedouro | Encontra Bebedouro","headline":"GCM aumenta patrulhamento na regi\u00e3o central de Bebedouro","author":{"@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/author\/ebebedouro\/#author"},"publisher":{"@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/#organization"},"datePublished":"2012-12-14T11:14:42-02:00","dateModified":"2019-04-29T17:12:15-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\/#webpage"},"isPartOf":{"@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\/#webpage"},"articleSection":"Not\u00edcias Bebedouro"},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre#listItem","position":1,"name":"Dom\u00e9stica","item":"https:\/\/www.encontrabebedouro.com.br\/sobre","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/noticias-bebedouro\/#listItem","name":"Not\u00edcias Bebedouro"}},{"@type":"ListItem","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/noticias-bebedouro\/#listItem","position":2,"name":"Not\u00edcias Bebedouro","item":"https:\/\/www.encontrabebedouro.com.br\/sobre\/noticias-bebedouro\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\/#listItem","name":"GCM aumenta patrulhamento na regi\u00e3o central de Bebedouro"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre#listItem","name":"Dom\u00e9stica"}},{"@type":"ListItem","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\/#listItem","position":3,"name":"GCM aumenta patrulhamento na regi\u00e3o central de Bebedouro","previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/noticias-bebedouro\/#listItem","name":"Not\u00edcias Bebedouro"}}]},{"@type":"Organization","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/#organization","name":"Encontra Bebedouro","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Bebedouro e regi\u00e3o","url":"https:\/\/www.encontrabebedouro.com.br\/sobre\/"},{"@type":"Person","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/author\/ebebedouro\/#author","url":"https:\/\/www.encontrabebedouro.com.br\/sobre\/author\/ebebedouro\/","name":"Encontra Bebedouro","image":{"@type":"ImageObject","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","width":96,"height":96,"caption":"Encontra Bebedouro"}},{"@type":"WebPage","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\/#webpage","url":"https:\/\/www.encontrabebedouro.com.br\/sobre\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\/","name":"GCM aumenta patrulhamento na regi\u00e3o central de Bebedouro | Encontra Bebedouro","description":"A Guarda Civil Municipal vai aumentar o patrulhamento na regi\u00e3o central da cidade, devido \u00e0s festas de final de ano. O comandante da GCM, Luiz Roberto Cardos, disse \u201co objetivo principal \u00e9 diminuir o numero de furtos e roubos. O n\u00famero de pessoas circulando pelo com\u00e9rcio aumenta neste per\u00edodo do ano, e os ladr\u00f5es aproveitam","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/#website"},"breadcrumb":{"@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\/#breadcrumblist"},"author":{"@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/author\/ebebedouro\/#author"},"creator":{"@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/author\/ebebedouro\/#author"},"datePublished":"2012-12-14T11:14:42-02:00","dateModified":"2019-04-29T17:12:15-03:00"},{"@type":"WebSite","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/#website","url":"https:\/\/www.encontrabebedouro.com.br\/sobre\/","name":"Encontra Bebedouro","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Bebedouro e regi\u00e3o","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Encontra Bebedouro | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Bebedouro e regi\u00e3o","og:type":"article","og:title":"GCM aumenta patrulhamento na regi\u00e3o central de Bebedouro | Encontra Bebedouro","og:description":"A Guarda Civil Municipal vai aumentar o patrulhamento na regi\u00e3o central da cidade, devido \u00e0s festas de final de ano. O comandante da GCM, Luiz Roberto Cardos, disse \u201co objetivo principal \u00e9 diminuir o numero de furtos e roubos. O n\u00famero de pessoas circulando pelo com\u00e9rcio aumenta neste per\u00edodo do ano, e os ladr\u00f5es aproveitam","og:url":"https:\/\/www.encontrabebedouro.com.br\/sobre\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\/","article:published_time":"2012-12-14T13:14:42+00:00","article:modified_time":"2019-04-29T20:12:15+00:00","twitter:card":"summary_large_image","twitter:title":"GCM aumenta patrulhamento na regi\u00e3o central de Bebedouro | Encontra Bebedouro","twitter:description":"A Guarda Civil Municipal vai aumentar o patrulhamento na regi\u00e3o central da cidade, devido \u00e0s festas de final de ano. O comandante da GCM, Luiz Roberto Cardos, disse \u201co objetivo principal \u00e9 diminuir o numero de furtos e roubos. O n\u00famero de pessoas circulando pelo com\u00e9rcio aumenta neste per\u00edodo do ano, e os ladr\u00f5es aproveitam"},"aioseo_meta_data":{"post_id":"474","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2023-09-27 19:32:01","updated":"2026-08-05 18:58:34","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontrabebedouro.com.br\/sobre\" title=\"Dom\u00e9stica\">Dom\u00e9stica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontrabebedouro.com.br\/sobre\/noticias-bebedouro\/\" title=\"Not\u00edcias Bebedouro\">Not\u00edcias Bebedouro<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tGCM aumenta patrulhamento na regi\u00e3o central de Bebedouro\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Dom\u00e9stica","link":"https:\/\/www.encontrabebedouro.com.br\/sobre"},{"label":"Not\u00edcias Bebedouro","link":"https:\/\/www.encontrabebedouro.com.br\/sobre\/noticias-bebedouro\/"},{"label":"GCM aumenta patrulhamento na regi\u00e3o central de Bebedouro","link":"https:\/\/www.encontrabebedouro.com.br\/sobre\/gcm-aumenta-patrulhamento-na-regiao-central-de-bebedouro\/"}],"_links":{"self":[{"href":"https:\/\/www.encontrabebedouro.com.br\/sobre\/wp-json\/wp\/v2\/posts\/474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabebedouro.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabebedouro.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabebedouro.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabebedouro.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=474"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabebedouro.com.br\/sobre\/wp-json\/wp\/v2\/posts\/474\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabebedouro.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabebedouro.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabebedouro.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}