{"id":156,"date":"2012-03-13T09:02:36","date_gmt":"2012-03-13T11:02:36","guid":{"rendered":"http:\/\/www.encontrabebedouro.com.br\/noticias\/?p=156"},"modified":"2019-04-29T17:13:31","modified_gmt":"2019-04-29T20:13:31","slug":"caminhada-pense-rosa-atrai-centenas-de-participantes","status":"publish","type":"post","link":"https:\/\/www.encontrabebedouro.com.br\/sobre\/caminhada-pense-rosa-atrai-centenas-de-participantes\/","title":{"rendered":"Caminhada Pense Rosa atrai centenas de participantes"},"content":{"rendered":"<div class=\"e7593ce1d9603c7e10386aa266b728a9\" data-index=\"1\" style=\"float: left; margin: 15px 15px 15px 0;\">\n<!-- EBR \/Novo-Bairro\/ 300x250 - pub-85 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:300px;height:250px\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"4691134188\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\r\n\n<\/div>\n<p>Para encerrar a programa\u00e7\u00e3o da Semana da Mulher, aconteceu s\u00e1bado (10\/3) a Caminhada Pense Rosa, com o objetivo de conscientizar a popula\u00e7\u00e3o sobre a import\u00e2ncia da preven\u00e7\u00e3o ao c\u00e2ncer de mama e ao colo do \u00fatero e de arrecadar produtos utilizados no Hospital Municipal.<\/p>\n<p>Os participantes, concentrados em frente \u00e0 Prefeitura, participaram de sess\u00f5es de alongamento e assistiram a n\u00fameros de dan\u00e7a. Presen\u00e7a do prefeito da cidade Bebedouro, o Italiano, e da presidente do Fundo Social de Solidariedade, primeira-dama Sueli Bianchini.<\/p>\n<p>A caminhada teve in\u00edcio \u00e0s 10h, em dire\u00e7\u00e3o \u00e0 Concha Ac\u00fastica, com a participa\u00e7\u00e3o especial dos ex-BBBs, Adriana e Rodrig\u00e3o. Mais de 300 pessoas, entre homens e mulheres, percorreram as ruas do centro da cidade, a grande maioria trajada com camiseta rosa.<\/p>\n<p>Os ex-BBs disseram que pela primeira vez participavam de uma a\u00e7\u00e3o de preven\u00e7\u00e3o, com orienta\u00e7\u00e3o voltada para a import\u00e2ncia do auto-exame e da mamografia. \u201cQue as mulheres possam se conscientizar de que devem fazer o auto-exame e a mamografia regularmente, pois isso pode salvar vidas!\u201d, observaram Adriana e Rodrig\u00e3o.<\/p>\n<p>O evento contou com o apoio da Prefeitura, do ICDH (Instituto de Compromisso com o Desenvolvimento Humano), da Unimed Bebedouro, da Delegacia de Defesa da Mulher, do Cram, do Conselho Municipal de Defesa dos Direitos da Mulher, do Hospital de C\u00e2ncer de Barretos, da Funda\u00e7\u00e3o Ab\u00edlio Alves Marques, do Unifafibe, da Droga Center, do Iquegami Supermercados, do Fundo Social de Solidariedade e do Depto. Municipal de Sa\u00fade (Programa DST\/Aids).<\/p>\n<p><strong>Atividade f\u00edsica<\/strong> &#8211; Na sexta-feira (9\/3), em frente \u00e0 Prefeitura, a presidente do FSS, primeira-dama Sueli Bianchini, junto com funcion\u00e1rios municipais, participou de aulas de dan\u00e7as. O evento foi coordenado pelos professores do DME, os g\u00eameos Edgar e Evair Joaquim da Costa, em comemora\u00e7\u00e3o ao Dia Internacional da Mulher.<\/p>\n<p><em>Fonte: Prefeitura de Bebedouro<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Para encerrar a programa\u00e7\u00e3o da Semana da Mulher, aconteceu s\u00e1bado (10\/3) a Caminhada Pense Rosa, com o objetivo de conscientizar a popula\u00e7\u00e3o sobre a import\u00e2ncia da preven\u00e7\u00e3o ao c\u00e2ncer de mama e ao colo do \u00fatero e de arrecadar produtos utilizados no Hospital Municipal. Os participantes, concentrados em frente \u00e0 Prefeitura, participaram de sess\u00f5es de alongamento e assistiram a n\u00fameros de dan\u00e7a. Presen\u00e7a do prefeito da cidade Bebedouro, o Italiano, e da presidente do Fundo Social de Solidariedade, primeira-dama Sueli Bianchini. A caminhada teve in\u00edcio \u00e0s 10h, em dire\u00e7\u00e3o \u00e0 Concha Ac\u00fastica, com a participa\u00e7\u00e3o especial dos ex-BBBs, Adriana e <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-156","post","type-post","status-publish","format-standard","hentry","category-noticias-bebedouro"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Para encerrar a programa\u00e7\u00e3o da Semana da Mulher, aconteceu s\u00e1bado (10\/3) a Caminhada Pense Rosa, com o objetivo de conscientizar a popula\u00e7\u00e3o sobre a import\u00e2ncia da preven\u00e7\u00e3o ao c\u00e2ncer de mama e ao colo do \u00fatero e de arrecadar produtos utilizados no Hospital Municipal. Os participantes, concentrados em frente \u00e0 Prefeitura, participaram de sess\u00f5es de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Encontra Bebedouro\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.encontrabebedouro.com.br\/sobre\/caminhada-pense-rosa-atrai-centenas-de-participantes\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Encontra Bebedouro | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Bebedouro e regi\u00e3o\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Caminhada Pense Rosa atrai centenas de participantes | Encontra Bebedouro\" \/>\n\t\t<meta property=\"og:description\" content=\"Para encerrar a programa\u00e7\u00e3o da Semana da Mulher, aconteceu s\u00e1bado (10\/3) a Caminhada Pense Rosa, com o objetivo de conscientizar a popula\u00e7\u00e3o sobre a import\u00e2ncia da preven\u00e7\u00e3o ao c\u00e2ncer de mama e ao colo do \u00fatero e de arrecadar produtos utilizados no Hospital Municipal. Os participantes, concentrados em frente \u00e0 Prefeitura, participaram de sess\u00f5es de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.encontrabebedouro.com.br\/sobre\/caminhada-pense-rosa-atrai-centenas-de-participantes\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2012-03-13T11:02:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-04-29T20:13:31+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Caminhada Pense Rosa atrai centenas de participantes | Encontra Bebedouro\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Para encerrar a programa\u00e7\u00e3o da Semana da Mulher, aconteceu s\u00e1bado (10\/3) a Caminhada Pense Rosa, com o objetivo de conscientizar a popula\u00e7\u00e3o sobre a import\u00e2ncia da preven\u00e7\u00e3o ao c\u00e2ncer de mama e ao colo do \u00fatero e de arrecadar produtos utilizados no Hospital Municipal. Os participantes, concentrados em frente \u00e0 Prefeitura, participaram de sess\u00f5es de\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/caminhada-pense-rosa-atrai-centenas-de-participantes\\\/#article\",\"name\":\"Caminhada Pense Rosa atrai centenas de participantes | Encontra Bebedouro\",\"headline\":\"Caminhada Pense Rosa atrai centenas de participantes\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/author\\\/ebebedouro\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/#organization\"},\"datePublished\":\"2012-03-13T09:02:36-03:00\",\"dateModified\":\"2019-04-29T17:13:31-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/caminhada-pense-rosa-atrai-centenas-de-participantes\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/caminhada-pense-rosa-atrai-centenas-de-participantes\\\/#webpage\"},\"articleSection\":\"Not\\u00edcias Bebedouro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/caminhada-pense-rosa-atrai-centenas-de-participantes\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre#listItem\",\"position\":1,\"name\":\"Dom\\u00e9stica\",\"item\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/noticias-bebedouro\\\/#listItem\",\"name\":\"Not\\u00edcias Bebedouro\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/noticias-bebedouro\\\/#listItem\",\"position\":2,\"name\":\"Not\\u00edcias Bebedouro\",\"item\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/noticias-bebedouro\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/caminhada-pense-rosa-atrai-centenas-de-participantes\\\/#listItem\",\"name\":\"Caminhada Pense Rosa atrai centenas de participantes\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre#listItem\",\"name\":\"Dom\\u00e9stica\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/caminhada-pense-rosa-atrai-centenas-de-participantes\\\/#listItem\",\"position\":3,\"name\":\"Caminhada Pense Rosa atrai centenas de participantes\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/noticias-bebedouro\\\/#listItem\",\"name\":\"Not\\u00edcias Bebedouro\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/#organization\",\"name\":\"Encontra Bebedouro\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Bebedouro e regi\\u00e3o\",\"url\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/author\\\/ebebedouro\\\/#author\",\"url\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/author\\\/ebebedouro\\\/\",\"name\":\"Encontra Bebedouro\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/caminhada-pense-rosa-atrai-centenas-de-participantes\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Encontra Bebedouro\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/caminhada-pense-rosa-atrai-centenas-de-participantes\\\/#webpage\",\"url\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/caminhada-pense-rosa-atrai-centenas-de-participantes\\\/\",\"name\":\"Caminhada Pense Rosa atrai centenas de participantes | Encontra Bebedouro\",\"description\":\"Para encerrar a programa\\u00e7\\u00e3o da Semana da Mulher, aconteceu s\\u00e1bado (10\\\/3) a Caminhada Pense Rosa, com o objetivo de conscientizar a popula\\u00e7\\u00e3o sobre a import\\u00e2ncia da preven\\u00e7\\u00e3o ao c\\u00e2ncer de mama e ao colo do \\u00fatero e de arrecadar produtos utilizados no Hospital Municipal. Os participantes, concentrados em frente \\u00e0 Prefeitura, participaram de sess\\u00f5es de\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/caminhada-pense-rosa-atrai-centenas-de-participantes\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/author\\\/ebebedouro\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/author\\\/ebebedouro\\\/#author\"},\"datePublished\":\"2012-03-13T09:02:36-03:00\",\"dateModified\":\"2019-04-29T17:13:31-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/\",\"name\":\"Encontra Bebedouro\",\"description\":\"Not\\u00edcias, eventos, informa\\u00e7\\u00f5es e dicas na cidade de Bebedouro e regi\\u00e3o\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.encontrabebedouro.com.br\\\/sobre\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Caminhada Pense Rosa atrai centenas de participantes | Encontra Bebedouro","description":"Para encerrar a programa\u00e7\u00e3o da Semana da Mulher, aconteceu s\u00e1bado (10\/3) a Caminhada Pense Rosa, com o objetivo de conscientizar a popula\u00e7\u00e3o sobre a import\u00e2ncia da preven\u00e7\u00e3o ao c\u00e2ncer de mama e ao colo do \u00fatero e de arrecadar produtos utilizados no Hospital Municipal. Os participantes, concentrados em frente \u00e0 Prefeitura, participaram de sess\u00f5es de","canonical_url":"https:\/\/www.encontrabebedouro.com.br\/sobre\/caminhada-pense-rosa-atrai-centenas-de-participantes\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/caminhada-pense-rosa-atrai-centenas-de-participantes\/#article","name":"Caminhada Pense Rosa atrai centenas de participantes | Encontra Bebedouro","headline":"Caminhada Pense Rosa atrai centenas de participantes","author":{"@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/author\/ebebedouro\/#author"},"publisher":{"@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/#organization"},"datePublished":"2012-03-13T09:02:36-03:00","dateModified":"2019-04-29T17:13:31-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/caminhada-pense-rosa-atrai-centenas-de-participantes\/#webpage"},"isPartOf":{"@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/caminhada-pense-rosa-atrai-centenas-de-participantes\/#webpage"},"articleSection":"Not\u00edcias Bebedouro"},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/caminhada-pense-rosa-atrai-centenas-de-participantes\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre#listItem","position":1,"name":"Dom\u00e9stica","item":"https:\/\/www.encontrabebedouro.com.br\/sobre","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/noticias-bebedouro\/#listItem","name":"Not\u00edcias Bebedouro"}},{"@type":"ListItem","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/noticias-bebedouro\/#listItem","position":2,"name":"Not\u00edcias Bebedouro","item":"https:\/\/www.encontrabebedouro.com.br\/sobre\/noticias-bebedouro\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/caminhada-pense-rosa-atrai-centenas-de-participantes\/#listItem","name":"Caminhada Pense Rosa atrai centenas de participantes"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre#listItem","name":"Dom\u00e9stica"}},{"@type":"ListItem","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/caminhada-pense-rosa-atrai-centenas-de-participantes\/#listItem","position":3,"name":"Caminhada Pense Rosa atrai centenas de participantes","previousItem":{"@type":"ListItem","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/noticias-bebedouro\/#listItem","name":"Not\u00edcias Bebedouro"}}]},{"@type":"Organization","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/#organization","name":"Encontra Bebedouro","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Bebedouro e regi\u00e3o","url":"https:\/\/www.encontrabebedouro.com.br\/sobre\/"},{"@type":"Person","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/author\/ebebedouro\/#author","url":"https:\/\/www.encontrabebedouro.com.br\/sobre\/author\/ebebedouro\/","name":"Encontra Bebedouro","image":{"@type":"ImageObject","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/caminhada-pense-rosa-atrai-centenas-de-participantes\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/507340682b8270222e1f208e23198b6ae7e2c6a1033ae84e99bc6bce4f82a387?s=96&d=mm&r=g","width":96,"height":96,"caption":"Encontra Bebedouro"}},{"@type":"WebPage","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/caminhada-pense-rosa-atrai-centenas-de-participantes\/#webpage","url":"https:\/\/www.encontrabebedouro.com.br\/sobre\/caminhada-pense-rosa-atrai-centenas-de-participantes\/","name":"Caminhada Pense Rosa atrai centenas de participantes | Encontra Bebedouro","description":"Para encerrar a programa\u00e7\u00e3o da Semana da Mulher, aconteceu s\u00e1bado (10\/3) a Caminhada Pense Rosa, com o objetivo de conscientizar a popula\u00e7\u00e3o sobre a import\u00e2ncia da preven\u00e7\u00e3o ao c\u00e2ncer de mama e ao colo do \u00fatero e de arrecadar produtos utilizados no Hospital Municipal. Os participantes, concentrados em frente \u00e0 Prefeitura, participaram de sess\u00f5es de","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/#website"},"breadcrumb":{"@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/caminhada-pense-rosa-atrai-centenas-de-participantes\/#breadcrumblist"},"author":{"@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/author\/ebebedouro\/#author"},"creator":{"@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/author\/ebebedouro\/#author"},"datePublished":"2012-03-13T09:02:36-03:00","dateModified":"2019-04-29T17:13:31-03:00"},{"@type":"WebSite","@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/#website","url":"https:\/\/www.encontrabebedouro.com.br\/sobre\/","name":"Encontra Bebedouro","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Bebedouro e regi\u00e3o","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.encontrabebedouro.com.br\/sobre\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Encontra Bebedouro | Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas na cidade de Bebedouro e regi\u00e3o","og:type":"article","og:title":"Caminhada Pense Rosa atrai centenas de participantes | Encontra Bebedouro","og:description":"Para encerrar a programa\u00e7\u00e3o da Semana da Mulher, aconteceu s\u00e1bado (10\/3) a Caminhada Pense Rosa, com o objetivo de conscientizar a popula\u00e7\u00e3o sobre a import\u00e2ncia da preven\u00e7\u00e3o ao c\u00e2ncer de mama e ao colo do \u00fatero e de arrecadar produtos utilizados no Hospital Municipal. Os participantes, concentrados em frente \u00e0 Prefeitura, participaram de sess\u00f5es de","og:url":"https:\/\/www.encontrabebedouro.com.br\/sobre\/caminhada-pense-rosa-atrai-centenas-de-participantes\/","article:published_time":"2012-03-13T11:02:36+00:00","article:modified_time":"2019-04-29T20:13:31+00:00","twitter:card":"summary_large_image","twitter:title":"Caminhada Pense Rosa atrai centenas de participantes | Encontra Bebedouro","twitter:description":"Para encerrar a programa\u00e7\u00e3o da Semana da Mulher, aconteceu s\u00e1bado (10\/3) a Caminhada Pense Rosa, com o objetivo de conscientizar a popula\u00e7\u00e3o sobre a import\u00e2ncia da preven\u00e7\u00e3o ao c\u00e2ncer de mama e ao colo do \u00fatero e de arrecadar produtos utilizados no Hospital Municipal. Os participantes, concentrados em frente \u00e0 Prefeitura, participaram de sess\u00f5es de"},"aioseo_meta_data":{"post_id":"156","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2023-09-27 20:25:34","updated":"2026-08-05 17:20:25","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontrabebedouro.com.br\/sobre\" title=\"Dom\u00e9stica\">Dom\u00e9stica<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.encontrabebedouro.com.br\/sobre\/noticias-bebedouro\/\" title=\"Not\u00edcias Bebedouro\">Not\u00edcias Bebedouro<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCaminhada Pense Rosa atrai centenas de participantes\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Dom\u00e9stica","link":"https:\/\/www.encontrabebedouro.com.br\/sobre"},{"label":"Not\u00edcias Bebedouro","link":"https:\/\/www.encontrabebedouro.com.br\/sobre\/noticias-bebedouro\/"},{"label":"Caminhada Pense Rosa atrai centenas de participantes","link":"https:\/\/www.encontrabebedouro.com.br\/sobre\/caminhada-pense-rosa-atrai-centenas-de-participantes\/"}],"_links":{"self":[{"href":"https:\/\/www.encontrabebedouro.com.br\/sobre\/wp-json\/wp\/v2\/posts\/156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrabebedouro.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrabebedouro.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrabebedouro.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrabebedouro.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=156"}],"version-history":[{"count":0,"href":"https:\/\/www.encontrabebedouro.com.br\/sobre\/wp-json\/wp\/v2\/posts\/156\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontrabebedouro.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrabebedouro.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrabebedouro.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}